{"id":15729,"date":"2025-07-18T16:28:00","date_gmt":"2025-07-18T22:28:00","guid":{"rendered":"https:\/\/journey.app\/blog\/?p=15729"},"modified":"2025-09-05T21:02:02","modified_gmt":"2025-09-06T03:02:02","slug":"reglas-del-atletismo-de-pista","status":"publish","type":"post","link":"https:\/\/journey.app\/blog\/reglas-del-atletismo-de-pista\/","title":{"rendered":"Reglas del atletismo de pista: c\u00f3mo se compite"},"content":{"rendered":"\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><a href=\"https:\/\/journey.app\/?reference=JourneyBlog\"><img loading=\"lazy\" width=\"655\" height=\"240\" src=\"https:\/\/journey.app\/blog\/wp-content\/uploads\/2022\/02\/Banner-blog-2022_1.png\" alt=\"\" class=\"wp-image-11002\" srcset=\"https:\/\/journey.app\/blog\/wp-content\/uploads\/2022\/02\/Banner-blog-2022_1.png 655w, https:\/\/journey.app\/blog\/wp-content\/uploads\/2022\/02\/Banner-blog-2022_1-300x110.png 300w\" sizes=\"(max-width: 655px) 100vw, 655px\" \/><\/a><\/figure><\/div>\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2>\u00cdndice<\/h2>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><a href=\"#definicion-y-objetivo\">Definici\u00f3n y objetivo<\/a><\/p>\n\n\n\n<p><a href=\"#como-se-compite\">C\u00f3mo se compite<\/a><\/p>\n\n\n\n<p><a href=\"#faltas-y-penalizaciones\">Faltas y penalizaciones<\/a><\/p>\n\n\n\n<p><a href=\"#campo-de-juego\">Campo de juego<\/a><\/p>\n\n\n\n<p><a href=\"#equipo-deportivo\">Equipo deportivo<\/a><\/p>\n\n\n\n<p><a href=\"#uniformes-reglamentarios\">Uniformes reglamentarios<\/a><\/p>\n\n\n\n<p><a href=\"#v\">Reglas descargables<\/a><\/p>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Este deporte es el m\u00e1s antiguo que existe en el mundo y tambi\u00e9n es uno de los m\u00e1s sencillos de entender. Conoce m\u00e1s sobre las <strong>reglas del atletismo de pista<\/strong> para llegar bien preparado a tu pr\u00f3xima competencia. <\/p>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Reglas del atletismo de pista (carreras): \u00bfc\u00f3mo se compite?\" width=\"900\" height=\"506\" src=\"https:\/\/www.youtube.com\/embed\/s_16g5zrWmo?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><figcaption>Video: reglas del atletismo de pista<\/figcaption><\/figure>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<div class=\"wp-block-image is-style-rounded\">\n<figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" src=\"https:\/\/journey.app\/blog\/wp-content\/uploads\/2023\/08\/Angel-Bahena-Atletismo-682x1024.jpg\" alt=\"\" class=\"wp-image-16863\" width=\"341\" height=\"512\" srcset=\"https:\/\/journey.app\/blog\/wp-content\/uploads\/2023\/08\/Angel-Bahena-Atletismo-682x1024.jpg 682w, https:\/\/journey.app\/blog\/wp-content\/uploads\/2023\/08\/Angel-Bahena-Atletismo-200x300.jpg 200w, https:\/\/journey.app\/blog\/wp-content\/uploads\/2023\/08\/Angel-Bahena-Atletismo-768x1153.jpg 768w, https:\/\/journey.app\/blog\/wp-content\/uploads\/2023\/08\/Angel-Bahena-Atletismo-1023x1536.jpg 1023w, https:\/\/journey.app\/blog\/wp-content\/uploads\/2023\/08\/Angel-Bahena-Atletismo.jpg 1066w\" sizes=\"(max-width: 341px) 100vw, 341px\" \/><figcaption>FB: <a href=\"https:\/\/www.facebook.com\/profile.php?id=100076110103918\"><strong>ANBAR CLUB Atletismo<\/strong><\/a><\/figcaption><\/figure><\/div>\n\n\n<p class=\"has-text-align-center has-medium-font-size\"><em>Un agradecimiento especial a&nbsp;<strong><a href=\"https:\/\/www.facebook.com\/profile.php?id=100076110103918\">\u00c1ngel Bahena<\/a><\/strong>, fundador y entrenador en ANBAR Club Atletismo, quien nos apoy\u00f3 revisando este art\u00edculo.<\/em><\/p>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p class=\"has-medium-font-size\"><strong><em>Te puede interesar:<\/em><\/strong><\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong><em><a href=\"https:\/\/journey.app\/blog\/seguro-para-atletismo\/\">Seguro para atletismo: seguridad para todo atleta<\/a><\/em><\/strong><\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong><em><a href=\"https:\/\/journey.app\/blog\/lesiones-en-corredores-cuales-son-y-como-prevenirlas\/\">Lesiones en corredores: cu\u00e1les son y c\u00f3mo prevenirlas<\/a><\/em><\/strong><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" width=\"1024\" height=\"682\" src=\"https:\/\/journey.app\/blog\/wp-content\/uploads\/2023\/06\/carrera_Atletismo-1024x682.jpg\" alt=\"\" class=\"wp-image-15732\" srcset=\"https:\/\/journey.app\/blog\/wp-content\/uploads\/2023\/06\/carrera_Atletismo-1024x682.jpg 1024w, https:\/\/journey.app\/blog\/wp-content\/uploads\/2023\/06\/carrera_Atletismo-300x200.jpg 300w, https:\/\/journey.app\/blog\/wp-content\/uploads\/2023\/06\/carrera_Atletismo-768x512.jpg 768w, https:\/\/journey.app\/blog\/wp-content\/uploads\/2023\/06\/carrera_Atletismo-566x377.jpg 566w, https:\/\/journey.app\/blog\/wp-content\/uploads\/2023\/06\/carrera_Atletismo-390x260.jpg 390w, https:\/\/journey.app\/blog\/wp-content\/uploads\/2023\/06\/carrera_Atletismo-103x68.jpg 103w, https:\/\/journey.app\/blog\/wp-content\/uploads\/2023\/06\/carrera_Atletismo.jpg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div>\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"has-white-color has-text-color has-background\" id=\"definicion-y-objetivo\" style=\"background-color:#ff8f1c\">Definici\u00f3n y objetivo<\/h2>\n\n\n\n<div style=\"height:25px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>El atletismo de pista es una disciplina deportiva que <strong>consiste en completar carreras y diferentes pruebas de carreras, saltos y lanzamientos<\/strong> dentro de una pista cerrada o estadio. Este deporte es una de las formas m\u00e1s antiguas de competici\u00f3n atl\u00e9tica y una de las disciplinas fundamentales de los Juegos Ol\u00edmpicos.<\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Su objetivo principal es <strong>medir, cronometrar y mejorar<\/strong> las habilidades f\u00edsicas de los atletas en sus diferentes disciplinas, sobre todo la<strong> velocidad, la fuerza, la t\u00e9cnica y la destreza<\/strong>. Este deporte busca determinar qui\u00e9n es el competidor m\u00e1s r\u00e1pido, m\u00e1s fuerte o habilidoso seg\u00fan el tipo de prueba.<\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Las pruebas de pista al aire libre m\u00e1s comunes son:<\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<ul><li> <em style=\"font-weight: bold;\"><strong>Carreras de velocida<\/strong><\/em><em><strong>d masculinas: <\/strong><\/em>100 m, 200 m y 400 m, 110 m con vallas, 400 m con vallas, relevos 4&#215;100 m, 4&#215;400 m. Pruebas de medio fondo de 800 m y 1,500 m y de fondo de 5,000 m, 10,000 m y 3,000 m con obst\u00e1culos.<\/li><\/ul>\n\n\n\n<div style=\"height:25px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<ul><li>&#8211; <em><strong>Carreras de velocidad femeninas:<\/strong><\/em> 100 m, 200 m y 400 m, 100 m con vallas, 400 m con vallas, relevos 4&#215;100 m, 4&#215;400 m. Pruebas de medio fondo de 800 m y 1,500 m y de fondo\u00a0de 5,000 m, 10,000 m y 3,000 m con obst\u00e1culos.<\/li><\/ul>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>En el atletismo tambi\u00e9n hay eventos que consisten en salir de la pista y llegar al final, o s\u00f3lo llegar a la pista, como son la caminata y el marat\u00f3n. Tambi\u00e9n se realizan pruebas de campo como: salto de altura, salto con p\u00e9rtiga, salto de longitud y triple salto. Pruebas de lanzamiento de disco, lanzamiento de jabalina, lanzamiento de peso o bala y lanzamiento de martillo. Sin dejar afuera las pruebas combinadas de heptatl\u00f3n y decatl\u00f3n.\u00a0Sin embargo, en este art\u00edculo solo te hablar\u00e9 r\u00e1pidamente sobre las reglas del atletismo de pista para las diferentes pruebas de carrera.\u00a0<\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" width=\"1024\" height=\"631\" src=\"https:\/\/journey.app\/blog\/wp-content\/uploads\/2022\/03\/atletismo-1024x631.jpg\" alt=\"carreras de velocidad en el atletismo\" class=\"wp-image-11961\" srcset=\"https:\/\/journey.app\/blog\/wp-content\/uploads\/2022\/03\/atletismo-1024x631.jpg 1024w, https:\/\/journey.app\/blog\/wp-content\/uploads\/2022\/03\/atletismo-300x185.jpg 300w, https:\/\/journey.app\/blog\/wp-content\/uploads\/2022\/03\/atletismo-768x474.jpg 768w, https:\/\/journey.app\/blog\/wp-content\/uploads\/2022\/03\/atletismo-1536x947.jpg 1536w, https:\/\/journey.app\/blog\/wp-content\/uploads\/2022\/03\/atletismo-270x165.jpg 270w, https:\/\/journey.app\/blog\/wp-content\/uploads\/2022\/03\/atletismo.jpg 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div>\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"has-white-color has-text-color has-background\" id=\"como-se-compite\" style=\"background-color:#ff8f1c\">C\u00f3mo se compite<\/h2>\n\n\n\n<div style=\"height:25px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>En las reglas del atletismo para las pruebas de carrera, <strong>los competidores se enfrentan en una pista al aire libre de material sint\u00e9tico o arcilla, y deben recorrer lo m\u00e1s r\u00e1pido posible una distancia determinada<\/strong>. A continuaci\u00f3n, te dar\u00e9 una idea general de c\u00f3mo se compite en estas pruebas:<\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"has-text-color\" style=\"color:#ff8f1c\"><em>Salida<\/em><\/h3>\n\n\n\n<div style=\"height:25px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>La salida de una carrera estar\u00e1 se\u00f1alada por una l\u00ednea blanca. En todas las carreras que no se realicen por los carriles o calles individuales, la l\u00ednea de salida ser\u00e1 curvada, de tal manera que todos los atletas empiecen a la misma distancia de la meta. Para todas las pruebas de cualquier distancia las posiciones de salida ser\u00e1n numeradas de izquierda a derecha en el sentido de la carrera.<\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>En la pruebas de velocidad de hasta 400 m, se correr\u00e1 toda la distancia por su carril y sus voces de salida ser\u00e1n \u201c\u00a1A sus puestos!, \u00a1Listos!&#8221; y los corredores deben salir al disparo. La prueba de 800 m se correr\u00e1 por su carril hasta el borde m\u00e1s pr\u00f3ximo de la l\u00ednea del carril libre, lugar donde los atletas podr\u00e1n dejar sus respectivos carriles.<\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>En las pruebas de medio fondo y fondo sus voces de salida ser\u00e1n \u201c\u00a1A sus puestos!&#8221;, lo que indica que los corredores se deben acercar a la l\u00ednea de salida y salir con el disparo al carril libre.<\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"has-text-color\" style=\"color:#ff8f1c\"><em>Fin de la carrera<\/em><\/h3>\n\n\n\n<div style=\"height:25px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Seg\u00fan la modalidad, la carrera finaliza cuando los competidores cruzan la meta o cuando han completado el n\u00famero establecido de vueltas al circuito, el orden de llegada determina al ganador. En algunas pruebas, como las de velocidad, se utiliza un sistema de <em>fotofinish <\/em>para determinar el orden exacto de llegada cuando la diferencia entre los corredores es muy estrecha.<\/p>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"has-white-color has-text-color has-background\" id=\"faltas-y-penalizaciones\" style=\"background-color:#ff8f1c\">Faltas y penalizaciones<\/h2>\n\n\n\n<div style=\"height:25px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Todas las competencias en pista se rigen por las reglas de la <em><strong>World Athletics<\/strong><\/em>, existen ciertas faltas y penalizaciones que pueden ocurrir si un corredor no cumple con las reglas del atletismo establecidas. A continuaci\u00f3n las m\u00e1s comunes y sus penalizaciones:<\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<ul><li>&#8211; <em><strong>Salida falsa<\/strong><\/em>: si un corredor sale antes de que se d\u00e9 la se\u00f1al de inicio, se considera una salida falsa. En las competencias de alto nivel se utiliza un sistema de detecci\u00f3n para registrar cualquier movimiento prematuro. Cuando sucede una salida falsa, se penaliza al corredor con una descalificaci\u00f3n de la carrera.<\/li><\/ul>\n\n\n\n<div style=\"height:25px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<ul><li>&#8211; <strong><em>Cambio de carril<\/em><\/strong>: los corredores deben permanecer en sus carriles asignados durante la mayor parte de la carrera. Si un corredor cambia de carril sin una raz\u00f3n v\u00e1lida o sin espacio suficiente, puede recibir una advertencia por parte de los jueces. Si obtiene m\u00faltiples advertencias o comete una acci\u00f3n antideportiva, el corredor puede ser descalificado.<\/li><\/ul>\n\n\n\n<div style=\"height:25px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<ul><li>&#8211; <strong><em>Obstrucci\u00f3n<\/em><\/strong>: si un corredor obstruye intencionalmente a otro corredor, ya sea bloque\u00e1ndolo o interfiriendo en su carrera, puede recibir una advertencia o ser descalificado seg\u00fan la gravedad de la obstrucci\u00f3n.<\/li><\/ul>\n\n\n\n<div style=\"height:25px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<ul><li>&#8211;<em><strong> Zancadillas o contacto ilegal<\/strong><\/em>: cualquier situaci\u00f3n en la que un corredor intente hacer tropezar a otro corredor o entre en contacto f\u00edsico de manera antideportiva, puede resultar en una descalificaci\u00f3n inmediata.<\/li><\/ul>\n\n\n\n<div style=\"height:25px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<ul><li>&#8211; <em><strong>Salida incorrecta en relevos<\/strong><\/em>: esto sucede cuando un corredor se adelanta antes de que su compa\u00f1ero haya pasado un punto espec\u00edfico en la zona de cambio para intercambiar el testigo, esta falta se puede penalizar con descalificaci\u00f3n.<\/li><\/ul>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Es importante mencionar que las faltas y las penalizaciones pueden variar ligeramente seg\u00fan las regulaciones espec\u00edficas de la competencia y la categor\u00eda en la que se est\u00e9 compitiendo. Los jueces y \u00e1rbitros son los encargados de hacer cumplir las reglas y tomar las decisiones sobre las penalizaciones en cada caso.<\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" width=\"1024\" height=\"682\" src=\"https:\/\/journey.app\/blog\/wp-content\/uploads\/2023\/06\/atletismo-2-1024x682.jpg\" alt=\"\" class=\"wp-image-15736\" srcset=\"https:\/\/journey.app\/blog\/wp-content\/uploads\/2023\/06\/atletismo-2-1024x682.jpg 1024w, https:\/\/journey.app\/blog\/wp-content\/uploads\/2023\/06\/atletismo-2-300x200.jpg 300w, https:\/\/journey.app\/blog\/wp-content\/uploads\/2023\/06\/atletismo-2-768x512.jpg 768w, https:\/\/journey.app\/blog\/wp-content\/uploads\/2023\/06\/atletismo-2-566x377.jpg 566w, https:\/\/journey.app\/blog\/wp-content\/uploads\/2023\/06\/atletismo-2-390x260.jpg 390w, https:\/\/journey.app\/blog\/wp-content\/uploads\/2023\/06\/atletismo-2-103x68.jpg 103w, https:\/\/journey.app\/blog\/wp-content\/uploads\/2023\/06\/atletismo-2.jpg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div>\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"has-white-color has-text-color has-background\" id=\"campo-de-juego\" style=\"background-color:#ff8f1c\">Pista de atletismo<\/h2>\n\n\n\n<div style=\"height:25px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>En las reglas del atletismo de pista, se debe cumplir con las caracter\u00edsticas establecidas por la <strong><a href=\"https:\/\/worldathletics.org\/\">Federaci\u00f3n Internacional de Atletismo (World Athletics)<\/a><\/strong>. A continuaci\u00f3n, te proporcionar\u00e9 una descripci\u00f3n general de las caracter\u00edsticas de la pista de atletismo:<\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"has-text-color\" style=\"color:#ff8f1c\"><em>Superficie<\/em><\/h3>\n\n\n\n<div style=\"height:25px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>La superficie en la pista de atletismo generalmente est\u00e1 compuesta de un <strong>material sint\u00e9tico conocido como &#8220;tart\u00e1n<\/strong>&#8220;. Esta superficie es ideal pues proporciona una buena tracci\u00f3n para los atletas y minimiza el impacto en las articulaciones. Sin embargo, es posible usar pistas de tierra o c\u00e9sped en algunos lugares.<\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"has-text-color\" style=\"color:#ff8f1c\"><em>Forma y dimensiones<\/em><\/h3>\n\n\n\n<div style=\"height:25px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>La pista de atletismo debe tener una <strong>forma ovalada y estar compuesta de dos rectas y dos curvas<\/strong>. Las curvas deben tener un radio espec\u00edfico para asegurar distancias iguales entre los carriles y las rectas, la <strong>longitud total de la pista debe ser de 400 metros<\/strong>.<\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"has-text-color\" style=\"color:#ff8f1c\"><em>Calles de carrera<\/em><\/h3>\n\n\n\n<div style=\"height:25px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>La pista se divide en <strong>calles numeradas<\/strong> que permiten que los corredores se mantengan en su carril asignado durante la carrera. Generalmente, <strong>hay entre 6 y 9 calles en la pista<\/strong>.<\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"has-text-color\" style=\"color:#ff8f1c\"><em>Marcas y l\u00edneas<\/em><\/h3>\n\n\n\n<div style=\"height:25px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>La pista de atletismo debe tener l\u00edneas marcadas en diferentes puntos, la l\u00ednea de salida se encuentra en la recta inicial y la l\u00ednea de meta est\u00e1 ubicada en la recta final. Tambi\u00e9n se usan marcas para indicar las distancias de las pruebas, como los 100 metros y los 200 metros.<\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"has-text-color\" style=\"color:#ff8f1c\"><em>Zonas de cambio en relevos<\/em><\/h3>\n\n\n\n<div style=\"height:25px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>En las carreras de relevos hay puntos espec\u00edficos en los que los corredores deben <strong>realizar el intercambio del testigo entre los miembros del equipo<\/strong>. Estas zonas suelen estar marcadas en la pista y tienen una longitud espec\u00edfica para garantizar una transici\u00f3n adecuada.<\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Cabe recalcar que las dimensiones exactas y especificaciones <strong>pueden variar ligeramente seg\u00fan el tipo de pista y las regulaciones locales<\/strong>. Para las competencias de alto nivel, como los Juegos Ol\u00edmpicos o campeonatos mundiales, se deben seguir estrictamente las normas y est\u00e1ndares establecidos por las organizaciones deportivas internacionales.<\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" width=\"1024\" height=\"682\" src=\"https:\/\/journey.app\/blog\/wp-content\/uploads\/2023\/06\/pista-de-atletismo-1024x682.jpg\" alt=\"Pista de competencia en las reglas del atletismo\" class=\"wp-image-15734\" srcset=\"https:\/\/journey.app\/blog\/wp-content\/uploads\/2023\/06\/pista-de-atletismo-1024x682.jpg 1024w, https:\/\/journey.app\/blog\/wp-content\/uploads\/2023\/06\/pista-de-atletismo-300x200.jpg 300w, https:\/\/journey.app\/blog\/wp-content\/uploads\/2023\/06\/pista-de-atletismo-768x512.jpg 768w, https:\/\/journey.app\/blog\/wp-content\/uploads\/2023\/06\/pista-de-atletismo-566x377.jpg 566w, https:\/\/journey.app\/blog\/wp-content\/uploads\/2023\/06\/pista-de-atletismo-390x260.jpg 390w, https:\/\/journey.app\/blog\/wp-content\/uploads\/2023\/06\/pista-de-atletismo-103x68.jpg 103w, https:\/\/journey.app\/blog\/wp-content\/uploads\/2023\/06\/pista-de-atletismo.jpg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div>\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"has-white-color has-text-color has-background\" id=\"equipo-deportivo\" style=\"background-color:#ff8f1c\">Equipo deportivo<\/h2>\n\n\n\n<div style=\"height:25px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Los atletas deben usar un conjunto b\u00e1sico de equipo deportivo que les proporciona comodidad, seguridad y rendimiento durante la carrera. Aqu\u00ed te explico algunos elementos clave del equipo utilizado seg\u00fan las reglas del atletismo de pista:<\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<ul><li>&#8211; <strong><em>Tenis de carrera<\/em><\/strong>: aunque el reglamento te permite correr descalzo sin problemas, los tenis de carrera son uno de los elementos m\u00e1s importantes del equipo deportivo. Est\u00e1n dise\u00f1ados espec\u00edficamente para brindar tracci\u00f3n, amortiguaci\u00f3n y soporte al pie durante la carrera. Los tenis de pista suelen ser ligeros y tienen clavos o tacos en la suela para mejorar el agarre en la superficie de la pista.<\/li><\/ul>\n\n\n\n<div style=\"height:25px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<ul><li>&#8211; <em><strong>N\u00famero de competencia<\/strong><\/em>: los atletas deben llevar un n\u00famero de competencia en el pecho o en la espalda. Este n\u00famero es importante pues se utiliza para identificar a los competidores durante la carrera y para registrar los resultados y tiempos obtenidos.<\/li><\/ul>\n\n\n\n<div style=\"height:25px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<ul><li>&#8211; <em><strong>Accesorios opcionales<\/strong><\/em>: en las reglas del atletismo de pista se permiten accesorios adicionales como gorras, viseras, mu\u00f1equeras o gafas de sol, para protegerse o mejorar su comodidad durante la carrera.<\/li><\/ul>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"has-white-color has-text-color has-background\" id=\"uniformes-reglamentarios\" style=\"background-color:#ff8f1c\">Uniformes reglamentarios<\/h2>\n\n\n\n<div style=\"height:25px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>En las reglas del atletismo de pista existen ciertas especificaciones sobre los uniformes en las pruebas de carrera.&nbsp; A continuaci\u00f3n, te explicar\u00e9 algunas de las reglas b\u00e1sicas relacionadas a los uniformes en el atletismo de pista:<\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<ul><li>&#8211; <strong><em>Ropa deportiva<\/em><\/strong>: la ropa deportiva del uniforme debe ser ajustada y transpirable, como camisetas, <em>shorts <\/em>o mallas. Tambi\u00e9n, debe permitir la movilidad de los atletas y estar dise\u00f1ada para ayudar a regular la temperatura corporal y absorber el sudor.<\/li><\/ul>\n\n\n\n<div style=\"height:25px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<ul><li>&#8211; <strong><em>Tama\u00f1o y forma<\/em><\/strong>: los uniformes deben tener un tama\u00f1o y una forma apropiados que no otorguen ninguna ventaja injusta a los atletas. En las reglas del atletismo de pista no se permite el uso de prendas que puedan generar un efecto aerodin\u00e1mico excesivo o que puedan interferir con los movimientos naturales de los corredores.<\/li><\/ul>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Con esto concluye la breve explicaci\u00f3n sobre las reglas del atletismo de pista para las pruebas de carrera. Es importante recordar que las reglas espec\u00edficas pueden variar seg\u00fan el tipo de competencia, por lo que es recomendable consultar las regulaciones que aplican para tu evento.<\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" width=\"1024\" height=\"576\" src=\"https:\/\/journey.app\/blog\/wp-content\/uploads\/2023\/06\/reglas-atletismo_pista-1024x576.jpg\" alt=\"\" class=\"wp-image-15735\" srcset=\"https:\/\/journey.app\/blog\/wp-content\/uploads\/2023\/06\/reglas-atletismo_pista-1024x576.jpg 1024w, https:\/\/journey.app\/blog\/wp-content\/uploads\/2023\/06\/reglas-atletismo_pista-300x169.jpg 300w, https:\/\/journey.app\/blog\/wp-content\/uploads\/2023\/06\/reglas-atletismo_pista-768x432.jpg 768w, https:\/\/journey.app\/blog\/wp-content\/uploads\/2023\/06\/reglas-atletismo_pista.jpg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div>\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"has-white-color has-text-color has-background\" id=\"reglas-descargables\" style=\"background-color:#ff8f1c\">Reglas descargables<\/h2>\n\n\n\n<div style=\"height:25px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>A continuaci\u00f3n te comparto las reglas del atletismo de pista de World Athletics, en su idioma original y en formato PDF.<\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-file\"><object class=\"wp-block-file__embed\" data=\"https:\/\/journey.app\/blog\/wp-content\/uploads\/2023\/06\/reglas-atletismo_pista_EN.pdf\" type=\"application\/pdf\" style=\"width:100%;height:600px\" aria-label=\"Incrustado de reglas-atletismo_pista_EN.\"><\/object><a id=\"wp-block-file--media-e989a7b0-3bb3-48aa-b6a2-1a46ff032472\" href=\"https:\/\/journey.app\/blog\/wp-content\/uploads\/2023\/06\/reglas-atletismo_pista_EN.pdf\">reglas-atletismo_pista_EN<\/a><a href=\"https:\/\/journey.app\/blog\/wp-content\/uploads\/2023\/06\/reglas-atletismo_pista_EN.pdf\" class=\"wp-block-file__button\" download aria-describedby=\"wp-block-file--media-e989a7b0-3bb3-48aa-b6a2-1a46ff032472\"><\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u00cdndice Definici\u00f3n y objetivo C\u00f3mo se compite Faltas y penalizaciones Campo de juego Equipo deportivo Uniformes reglamentarios Reglas descargables Este deporte es el m\u00e1s antiguo que existe en el mundo y tambi\u00e9n es uno de los m\u00e1s sencillos de entender. Conoce m\u00e1s sobre las reglas del atletismo de pista para llegar bien preparado a tu [&hellip;]<\/p>\n","protected":false},"author":35,"featured_media":15740,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[347,553],"tags":[728,1102,1100,1101,568],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.7.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Reglas del atletismo de pista: c\u00f3mo se compite - Journey Sports<\/title>\n<meta name=\"description\" content=\"En este art\u00edculo podr\u00e1s encontrar informaci\u00f3n sobre las reglas del atletismo de pista y las pruebas de carrera.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/journey.app\/blog\/reglas-del-atletismo-de-pista\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Reglas del atletismo de pista: c\u00f3mo se compite - Journey Sports\" \/>\n<meta property=\"og:description\" content=\"En este art\u00edculo podr\u00e1s encontrar informaci\u00f3n sobre las reglas del atletismo de pista y las pruebas de carrera.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/journey.app\/blog\/reglas-del-atletismo-de-pista\/\" \/>\n<meta property=\"og:site_name\" content=\"Journey Sports\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/journeytheapp\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-18T22:28:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-06T03:02:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/journey.app\/blog\/wp-content\/uploads\/2023\/06\/atletismo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1279\" \/>\n\t<meta property=\"og:image:height\" content=\"877\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Celeste P\u00e9rez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@journey_the_app\" \/>\n<meta name=\"twitter:site\" content=\"@journey_the_app\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Celeste P\u00e9rez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/journey.app\/blog\/reglas-del-atletismo-de-pista\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/journey.app\/blog\/reglas-del-atletismo-de-pista\/\"},\"author\":{\"name\":\"Celeste P\u00e9rez\",\"@id\":\"https:\/\/journey.app\/blog\/#\/schema\/person\/c13b1227429c49b5e254a5a3942ebaa8\"},\"headline\":\"Reglas del atletismo de pista: c\u00f3mo se compite\",\"datePublished\":\"2025-07-18T22:28:00+00:00\",\"dateModified\":\"2025-09-06T03:02:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/journey.app\/blog\/reglas-del-atletismo-de-pista\/\"},\"wordCount\":1810,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/journey.app\/blog\/#organization\"},\"keywords\":[\"atletismo\",\"atletismo de pista\",\"reglas del atletismo\",\"reglas del atletismo de pista\",\"reglas deportivas\"],\"articleSection\":[\"Atletismo\",\"Reglas deportivas\"],\"inLanguage\":\"es-MX\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/journey.app\/blog\/reglas-del-atletismo-de-pista\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/journey.app\/blog\/reglas-del-atletismo-de-pista\/\",\"url\":\"https:\/\/journey.app\/blog\/reglas-del-atletismo-de-pista\/\",\"name\":\"Reglas del atletismo de pista: c\u00f3mo se compite - Journey Sports\",\"isPartOf\":{\"@id\":\"https:\/\/journey.app\/blog\/#website\"},\"datePublished\":\"2025-07-18T22:28:00+00:00\",\"dateModified\":\"2025-09-06T03:02:02+00:00\",\"description\":\"En este art\u00edculo podr\u00e1s encontrar informaci\u00f3n sobre las reglas del atletismo de pista y las pruebas de carrera.\",\"breadcrumb\":{\"@id\":\"https:\/\/journey.app\/blog\/reglas-del-atletismo-de-pista\/#breadcrumb\"},\"inLanguage\":\"es-MX\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/journey.app\/blog\/reglas-del-atletismo-de-pista\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/journey.app\/blog\/reglas-del-atletismo-de-pista\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/journey.app\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Reglas del atletismo de pista: c\u00f3mo se compite\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/journey.app\/blog\/#website\",\"url\":\"https:\/\/journey.app\/blog\/\",\"name\":\"Journey Sports\",\"description\":\"Blog enfocado en deportes y la salud del atleta. Encuentra historias de tu deporte favorito as\u00ed como recomendaciones de expertos en salud deportiva\",\"publisher\":{\"@id\":\"https:\/\/journey.app\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/journey.app\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es-MX\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/journey.app\/blog\/#organization\",\"name\":\"Journey App\",\"url\":\"https:\/\/journey.app\/blog\/\",\"sameAs\":[\"https:\/\/www.instagram.com\/journeytheapp\/\",\"https:\/\/www.linkedin.com\/company\/journey-social-network\/\",\"https:\/\/www.facebook.com\/journeytheapp\/\",\"https:\/\/twitter.com\/journey_the_app\"],\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-MX\",\"@id\":\"https:\/\/journey.app\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/journey.app\/blog\/wp-content\/uploads\/2019\/01\/journey-letras-negro.png\",\"contentUrl\":\"https:\/\/journey.app\/blog\/wp-content\/uploads\/2019\/01\/journey-letras-negro.png\",\"width\":160,\"height\":25,\"caption\":\"Journey App\"},\"image\":{\"@id\":\"https:\/\/journey.app\/blog\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/journey.app\/blog\/#\/schema\/person\/c13b1227429c49b5e254a5a3942ebaa8\",\"name\":\"Celeste P\u00e9rez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-MX\",\"@id\":\"https:\/\/journey.app\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/journey.app\/blog\/wp-content\/uploads\/2019\/01\/Celeste_2021_25-96x96.jpg\",\"contentUrl\":\"https:\/\/journey.app\/blog\/wp-content\/uploads\/2019\/01\/Celeste_2021_25-96x96.jpg\",\"caption\":\"Celeste P\u00e9rez\"},\"description\":\"Egresada de Negocios Internacionales apasionada por la vida activa y las actividades art\u00edsticas. En su adolescencia practic\u00f3 algunos deportes como nataci\u00f3n y boxeo, as\u00ed como futbol americano femenil durante un breve tiempo en su juventud. Actualmente realiza actividades de gimnasio, pilates y yoga para mantenerse saludable. Adem\u00e1s, disfruta mucho del arte, como la pintura, m\u00fasica, ver pel\u00edculas, leer libros y escribir. Su deporte favorito de ver es el futbol americano, el cual tambi\u00e9n es su deporte menos favorito de practicar.\",\"sameAs\":[\"https:\/\/www.linkedin.com\/in\/celeste-p\u00e9rez-50ba40212\/\"],\"url\":\"https:\/\/journey.app\/blog\/author\/celeste-perez\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Reglas del atletismo de pista: c\u00f3mo se compite - Journey Sports","description":"En este art\u00edculo podr\u00e1s encontrar informaci\u00f3n sobre las reglas del atletismo de pista y las pruebas de carrera.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/journey.app\/blog\/reglas-del-atletismo-de-pista\/","og_locale":"es_MX","og_type":"article","og_title":"Reglas del atletismo de pista: c\u00f3mo se compite - Journey Sports","og_description":"En este art\u00edculo podr\u00e1s encontrar informaci\u00f3n sobre las reglas del atletismo de pista y las pruebas de carrera.","og_url":"https:\/\/journey.app\/blog\/reglas-del-atletismo-de-pista\/","og_site_name":"Journey Sports","article_publisher":"https:\/\/www.facebook.com\/journeytheapp\/","article_published_time":"2025-07-18T22:28:00+00:00","article_modified_time":"2025-09-06T03:02:02+00:00","og_image":[{"width":1279,"height":877,"url":"https:\/\/journey.app\/blog\/wp-content\/uploads\/2023\/06\/atletismo.jpg","type":"image\/jpeg"}],"author":"Celeste P\u00e9rez","twitter_card":"summary_large_image","twitter_creator":"@journey_the_app","twitter_site":"@journey_the_app","twitter_misc":{"Written by":"Celeste P\u00e9rez","Est. reading time":"10 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/journey.app\/blog\/reglas-del-atletismo-de-pista\/#article","isPartOf":{"@id":"https:\/\/journey.app\/blog\/reglas-del-atletismo-de-pista\/"},"author":{"name":"Celeste P\u00e9rez","@id":"https:\/\/journey.app\/blog\/#\/schema\/person\/c13b1227429c49b5e254a5a3942ebaa8"},"headline":"Reglas del atletismo de pista: c\u00f3mo se compite","datePublished":"2025-07-18T22:28:00+00:00","dateModified":"2025-09-06T03:02:02+00:00","mainEntityOfPage":{"@id":"https:\/\/journey.app\/blog\/reglas-del-atletismo-de-pista\/"},"wordCount":1810,"commentCount":0,"publisher":{"@id":"https:\/\/journey.app\/blog\/#organization"},"keywords":["atletismo","atletismo de pista","reglas del atletismo","reglas del atletismo de pista","reglas deportivas"],"articleSection":["Atletismo","Reglas deportivas"],"inLanguage":"es-MX","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/journey.app\/blog\/reglas-del-atletismo-de-pista\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/journey.app\/blog\/reglas-del-atletismo-de-pista\/","url":"https:\/\/journey.app\/blog\/reglas-del-atletismo-de-pista\/","name":"Reglas del atletismo de pista: c\u00f3mo se compite - Journey Sports","isPartOf":{"@id":"https:\/\/journey.app\/blog\/#website"},"datePublished":"2025-07-18T22:28:00+00:00","dateModified":"2025-09-06T03:02:02+00:00","description":"En este art\u00edculo podr\u00e1s encontrar informaci\u00f3n sobre las reglas del atletismo de pista y las pruebas de carrera.","breadcrumb":{"@id":"https:\/\/journey.app\/blog\/reglas-del-atletismo-de-pista\/#breadcrumb"},"inLanguage":"es-MX","potentialAction":[{"@type":"ReadAction","target":["https:\/\/journey.app\/blog\/reglas-del-atletismo-de-pista\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/journey.app\/blog\/reglas-del-atletismo-de-pista\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/journey.app\/blog\/"},{"@type":"ListItem","position":2,"name":"Reglas del atletismo de pista: c\u00f3mo se compite"}]},{"@type":"WebSite","@id":"https:\/\/journey.app\/blog\/#website","url":"https:\/\/journey.app\/blog\/","name":"Journey Sports","description":"Blog enfocado en deportes y la salud del atleta. Encuentra historias de tu deporte favorito as\u00ed como recomendaciones de expertos en salud deportiva","publisher":{"@id":"https:\/\/journey.app\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/journey.app\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es-MX"},{"@type":"Organization","@id":"https:\/\/journey.app\/blog\/#organization","name":"Journey App","url":"https:\/\/journey.app\/blog\/","sameAs":["https:\/\/www.instagram.com\/journeytheapp\/","https:\/\/www.linkedin.com\/company\/journey-social-network\/","https:\/\/www.facebook.com\/journeytheapp\/","https:\/\/twitter.com\/journey_the_app"],"logo":{"@type":"ImageObject","inLanguage":"es-MX","@id":"https:\/\/journey.app\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/journey.app\/blog\/wp-content\/uploads\/2019\/01\/journey-letras-negro.png","contentUrl":"https:\/\/journey.app\/blog\/wp-content\/uploads\/2019\/01\/journey-letras-negro.png","width":160,"height":25,"caption":"Journey App"},"image":{"@id":"https:\/\/journey.app\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/journey.app\/blog\/#\/schema\/person\/c13b1227429c49b5e254a5a3942ebaa8","name":"Celeste P\u00e9rez","image":{"@type":"ImageObject","inLanguage":"es-MX","@id":"https:\/\/journey.app\/blog\/#\/schema\/person\/image\/","url":"https:\/\/journey.app\/blog\/wp-content\/uploads\/2019\/01\/Celeste_2021_25-96x96.jpg","contentUrl":"https:\/\/journey.app\/blog\/wp-content\/uploads\/2019\/01\/Celeste_2021_25-96x96.jpg","caption":"Celeste P\u00e9rez"},"description":"Egresada de Negocios Internacionales apasionada por la vida activa y las actividades art\u00edsticas. En su adolescencia practic\u00f3 algunos deportes como nataci\u00f3n y boxeo, as\u00ed como futbol americano femenil durante un breve tiempo en su juventud. Actualmente realiza actividades de gimnasio, pilates y yoga para mantenerse saludable. Adem\u00e1s, disfruta mucho del arte, como la pintura, m\u00fasica, ver pel\u00edculas, leer libros y escribir. Su deporte favorito de ver es el futbol americano, el cual tambi\u00e9n es su deporte menos favorito de practicar.","sameAs":["https:\/\/www.linkedin.com\/in\/celeste-p\u00e9rez-50ba40212\/"],"url":"https:\/\/journey.app\/blog\/author\/celeste-perez\/"}]}},"_links":{"self":[{"href":"https:\/\/journey.app\/blog\/wp-json\/wp\/v2\/posts\/15729"}],"collection":[{"href":"https:\/\/journey.app\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/journey.app\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/journey.app\/blog\/wp-json\/wp\/v2\/users\/35"}],"replies":[{"embeddable":true,"href":"https:\/\/journey.app\/blog\/wp-json\/wp\/v2\/comments?post=15729"}],"version-history":[{"count":16,"href":"https:\/\/journey.app\/blog\/wp-json\/wp\/v2\/posts\/15729\/revisions"}],"predecessor-version":[{"id":23125,"href":"https:\/\/journey.app\/blog\/wp-json\/wp\/v2\/posts\/15729\/revisions\/23125"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/journey.app\/blog\/wp-json\/wp\/v2\/media\/15740"}],"wp:attachment":[{"href":"https:\/\/journey.app\/blog\/wp-json\/wp\/v2\/media?parent=15729"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/journey.app\/blog\/wp-json\/wp\/v2\/categories?post=15729"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/journey.app\/blog\/wp-json\/wp\/v2\/tags?post=15729"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}<!-- This website is optimized by Airlift. Learn more: https://airlift.net. Template:. Learn more: https://airlift.net., Cached Timestamp: 2026-05-13 15:18:17 UTC -->